{"id":2702,"date":"2026-04-27T13:24:03","date_gmt":"2026-04-27T16:24:03","guid":{"rendered":"https:\/\/sistemafaeal.org.br\/faeal\/?p=2702"},"modified":"2026-05-11T13:58:45","modified_gmt":"2026-05-11T16:58:45","slug":"sistema-faeal-senar-destaca-sucesso-de-palestra-sobre-reforma-tributaria","status":"publish","type":"post","link":"https:\/\/sistemafaeal.org.br\/faeal\/sistema-faeal-senar-destaca-sucesso-de-palestra-sobre-reforma-tributaria\/","title":{"rendered":"Sistema Faeal\/Senar destaca sucesso de palestra sobre reforma tribut\u00e1ria"},"content":{"rendered":"<p><span style=\"font-weight: 400\">O Sistema Faeal\/Senar realizou, na quinta-feira (23), uma palestra online sobre reforma tribut\u00e1ria voltada ao setor produtivo rural. A iniciativa foi considerada um sucesso, reunindo produtores interessados em compreender os impactos das mudan\u00e7as no sistema tribut\u00e1rio brasileiro.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Segundo o presidente da institui\u00e7\u00e3o, \u00c1lvaro Almeida, os participantes que ainda tiverem d\u00favidas sobre o tema podem buscar esclarecimentos diretamente com a equipe t\u00e9cnica. O contato pode ser feito por meio da analista de Arrecada\u00e7\u00e3o, Carla Lima, pelo telefone (82) 9 8712 8521. Ela ficar\u00e1 respons\u00e1vel por encaminhar os questionamentos \u00e0 Confedera\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Brasil (CNA) e retornar com as orienta\u00e7\u00f5es aos produtores.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, o Sistema Faeal\/Senar informa que produtores que n\u00e3o conseguiram acompanhar a transmiss\u00e3o ao vivo poder\u00e3o ter uma nova oportunidade. A entidade avalia o reagendamento da palestra para retransmiss\u00e3o em data a ser divulgada, ampliando o acesso ao conte\u00fado a todos os produtores interessados.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Sistema Faeal\/Senar realizou, na quinta-feira (23), uma palestra online sobre reforma tribut\u00e1ria voltada ao setor produtivo rural. A iniciativa foi considerada um sucesso, reunindo produtores interessados em compreender os impactos das mudan\u00e7as no sistema tribut\u00e1rio brasileiro. Segundo o presidente da institui\u00e7\u00e3o, \u00c1lvaro Almeida, os participantes que ainda tiverem d\u00favidas sobre o tema podem buscar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[87,86,105,88],"tags":[],"class_list":["post-2702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-faeal","category-legislacao","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/posts\/2702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/comments?post=2702"}],"version-history":[{"count":1,"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/posts\/2702\/revisions"}],"predecessor-version":[{"id":2703,"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/posts\/2702\/revisions\/2703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/media\/2711"}],"wp:attachment":[{"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/media?parent=2702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/categories?post=2702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sistemafaeal.org.br\/faeal\/wp-json\/wp\/v2\/tags?post=2702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}